{"id":6190,"date":"2023-10-10T19:05:41","date_gmt":"2023-10-10T22:05:41","guid":{"rendered":"https:\/\/guiamania.com.br\/livro\/responsabilidade-humanistica-uma-proposta-para-agenda-esg-alexandre-seraphim-2\/"},"modified":"2023-10-11T01:36:36","modified_gmt":"2023-10-11T04:36:36","slug":"responsabilidade-humanistica-uma-proposta-para-agenda-esg-alexandre-seraphim-2","status":"publish","type":"post","link":"https:\/\/guiamania.com.br\/livro\/responsabilidade-humanistica-uma-proposta-para-agenda-esg-alexandre-seraphim-2\/","title":{"rendered":"Responsabilidade Human\u00edstica:: uma proposta para agenda ESG \u00bb Alexandre  Seraphim"},"content":{"rendered":"<p>O avan\u00e7o tecnol\u00f3gico do in\u00edcio deste s\u00e9culo trouxe in\u00fameras possibilidades para empresas quanto ao seu desenvolvimento, crescimento e prosperidade econ\u00f4mica. Muitas mudan\u00e7as ocorreram de forma acelerada no processo de trabalho, na produtividade e novas necessidades e neg\u00f3cios surgiram, as m\u00e1quinas foram definitivamente inseridas na vida das pessoas e ganharam protagonismo no cotidiano. A mesma velocidade que gerou mudan\u00e7as estruturais na rotina das pessoas e nos neg\u00f3cios, e que t\u00eam tido seus benef\u00edcios constantemente avaliados e questionados por especialistas, veio acompanhada tamb\u00e9m de graves problemas nas quest\u00f5es socioambientais, e mais: trouxe excessiva racionaliza\u00e7\u00e3o da vida, e consequentemente um processo de desumaniza\u00e7\u00e3o, uma quest\u00e3o cada vez mais preocupante e ainda n\u00e3o devidamente enfrentada. Foi essa preocupa\u00e7\u00e3o que deu origem ao livro \u201cResponsabilidade Human\u00edstica \u2013 uma proposta para a agenda ESG\u201d, do professor Dante Gallian e do executivo Alexandre Seraphim. Para os autores as empresas t\u00eam se posicionado, assumindo responsabilidades que v\u00e3o al\u00e9m do lucro e que se traduzem atualmente em compromissos com a agenda ambiental, social e de governan\u00e7a representados pela sigla ESG (environment, social and governance) mas para ambos, as empresas tamb\u00e9m podem introduzir a essa agenda mais uma responsabilidade, a Human\u00edstica, contribuindo para mitigar o problema, tornando essa pr\u00e1tica um s\u00f3lido alicerce para um desenvolvimento sustent\u00e1vel de fato, com lideran\u00e7as mais sens\u00edveis e com mais compreens\u00e3o sobre o que \u00e9 ser Humano. \u00c9 a Responsabilidade Human\u00edstica nas empresas que, segundo os autores, completa e fortalece a agenda ESG, traz os fundamentos das humanidades, como filosofia, artes e literatura. A metodologia do Laborat\u00f3rio de Leitura, que foi desenvolvida h\u00e1 mais de 15 anos pelo professor Gallian e tem como base a experi\u00eancia est\u00e9tico-reflexiva proporcionada pela literatura cl\u00e1ssica, j\u00e1 foi aplicada com sucesso em mais de uma dezena de empresas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O avan\u00e7o tecnol\u00f3gico do in\u00edcio deste s\u00e9culo trouxe in\u00fameras possibilidades para empresas quanto ao seu desenvolvimento, crescimento e prosperidade econ\u00f4mica. Muitas mudan\u00e7as ocorreram de forma acelerada no processo de trabalho, na produtividade e novas necessidades e neg\u00f3cios surgiram, as m\u00e1quinas foram definitivamente inseridas na vida das pessoas e ganharam protagonismo no cotidiano. A mesma velocidade [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"autor":[1227],"segmento":[629],"class_list":["post-6190","post","type-post","status-publish","format-standard","hentry","category-sem-categoria","autor-alexandre-seraphim","segmento-comportamento-organizacional"],"_links":{"self":[{"href":"https:\/\/guiamania.com.br\/livro\/wp-json\/wp\/v2\/posts\/6190","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/guiamania.com.br\/livro\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/guiamania.com.br\/livro\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/guiamania.com.br\/livro\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/guiamania.com.br\/livro\/wp-json\/wp\/v2\/comments?post=6190"}],"version-history":[{"count":0,"href":"https:\/\/guiamania.com.br\/livro\/wp-json\/wp\/v2\/posts\/6190\/revisions"}],"wp:attachment":[{"href":"https:\/\/guiamania.com.br\/livro\/wp-json\/wp\/v2\/media?parent=6190"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/guiamania.com.br\/livro\/wp-json\/wp\/v2\/categories?post=6190"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/guiamania.com.br\/livro\/wp-json\/wp\/v2\/tags?post=6190"},{"taxonomy":"autor","embeddable":true,"href":"https:\/\/guiamania.com.br\/livro\/wp-json\/wp\/v2\/autor?post=6190"},{"taxonomy":"segmento","embeddable":true,"href":"https:\/\/guiamania.com.br\/livro\/wp-json\/wp\/v2\/segmento?post=6190"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}